{"id":5165,"date":"2023-03-03T10:12:03","date_gmt":"2023-03-03T10:12:03","guid":{"rendered":"http:\/\/wintergudauri.com\/?page_id=5165"},"modified":"2023-03-07T14:56:32","modified_gmt":"2023-03-07T14:56:32","slug":"reservation-snowmobile","status":"publish","type":"page","link":"https:\/\/wintergudauri.com\/uk\/reservation-snowmobile\/","title":{"rendered":"\u0411\u0440\u043e\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u0435 \u0422\u0443\u0440 \u043d\u0430 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u0435"},"content":{"rendered":"<div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1645892568526 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpforms-container wpforms-container-full wpforms-stripe\" id=\"wpforms-5164\"><form id=\"wpforms-form-5164\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"5164\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/uk\/wp-json\/wp\/v2\/pages\/5165\" data-token=\"f3b19edb6b95216f91fece7bc0dd5770\" data-trp-original-action=\"\/uk\/wp-json\/wp\/v2\/pages\/5165\"><noscript class=\"wpforms-error-noscript\">\u0414\u043b\u044f \u0437\u0430\u043f\u043e\u0432\u043d\u0435\u043d\u043d\u044f \u0446\u0456\u0454\u0457 \u0444\u043e\u0440\u043c\u0438 \u0443\u0432\u0456\u043c\u043a\u043d\u0456\u0442\u044c JavaScript \u0443 \u0431\u0440\u0430\u0443\u0437\u0435\u0440\u0456.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-5164-field_5-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_5\">\u0414\u0430\u0442\u0430 <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-5164-field_5\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-large\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"1\" data-input=\"true\" name=\"wpforms[fields][5][date]\" required><a title=\"Clear Date\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-5164-field_12-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_12\">\u041f\u043e\u043b\u043e\u0432\u0438\u043d\u0430 \u0434\u043d\u044f<\/label><select id=\"wpforms-5164-field_12\" class=\"wpforms-field-large\" name=\"wpforms[fields][12]\"><option value=\"\u0423\u0442\u0440\u043e: \u0434\u043e 10:00\" >\u0423\u0442\u0440\u043e: \u0434\u043e 10:00<\/option><option value=\"\u041f\u043e\u0441\u043b\u0435 \u043e\u0431\u0435\u0434\u0430: \u0441 16:00\" >\u041f\u043e\u0441\u043b\u0435 \u043e\u0431\u0435\u0434\u0430: \u0441 16:00<\/option><\/select><\/div><div id=\"wpforms-5164-field_8-container\" class=\"wpforms-field wpforms-field-payment-select wpforms-field-select-style-classic\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_8\">\u0421\u043a\u043e\u043b\u044c\u043a\u043e \u0447\u0435\u043b\u043e\u0432\u0435\u043a \/ \u0446\u0435\u043d\u0430 <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-5164-field_8\" class=\"wpforms-payment-price wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][8]\" required=\"required\"><option value=\"1\" data-amount=\"25,00\"  selected='selected'>1 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434 \/ 125 \u20ac<\/option><option value=\"11\" data-amount=\"50,00\" >2 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u0430 \/ 250 \u20ac<\/option><option value=\"8\" data-amount=\"75,00\" >3 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u0430 \/ 375 \u20ac<\/option><option value=\"5\" data-amount=\"100,00\" >4 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u0430 \/ 500 \u20ac<\/option><option value=\"15\" data-amount=\"125,00\" >5 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u043e\u0432 \/ 625 \u20ac<\/option><\/select><\/div><div id=\"wpforms-5164-field_19-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"19\"><h3 id=\"wpforms-5164-field_19\" name=\"wpforms[fields][19]\">\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u043d\u0456 \u0434\u0430\u043d\u0456<\/h3><\/div><div id=\"wpforms-5164-field_21-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first\" data-field-id=\"21\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5164-field_21\">\u0406\u043c&#039;\u044f <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-5164-field_21\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][21]\" placeholder=\"\u0406\u043c&#039;\u044f\" required><\/div><div id=\"wpforms-5164-field_22-container\" class=\"wpforms-field wpforms-field-number wpforms-one-half\" data-field-id=\"22\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5164-field_22\">\u0412\u0456\u043a <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" pattern=\"\\d*\" id=\"wpforms-5164-field_22\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][22]\" placeholder=\"\u0412\u0456\u043a\" required><\/div><div id=\"wpforms-5164-field_17-container\" class=\"wpforms-field wpforms-field-phone wpforms-one-half wpforms-first\" data-field-id=\"17\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5164-field_17\">\u0422\u0435\u043b\u0435\u0444\u043e\u043d <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-5164-field_17\" class=\"wpforms-field-large wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][17]\" placeholder=\"\u041d\u043e\u043c\u0435\u0440 \u0442\u0435\u043b\u0435\u0444\u043e\u043d\u0443\" required><\/div><div id=\"wpforms-5164-field_18-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half\" data-field-id=\"18\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5164-field_18\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-5164-field_18\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][18]\" placeholder=\"Email\" required><\/div><div id=\"wpforms-5164-field_25-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-half wpforms-first wpforms-list-inline\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_25\">\u041c\u0435\u0441\u0435\u043d\u0434\u0436\u0435\u0440 <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-5164-field_25\" class=\"wpforms-field-required\"><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-5164-field_25_2\" name=\"wpforms[fields][25][]\" value=\"WhatsApp\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-5164-field_25_2\">WhatsApp<\/label><\/li><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-5164-field_25_1\" name=\"wpforms[fields][25][]\" value=\"Viber\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-5164-field_25_1\">Viber<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-5164-field_25_3\" name=\"wpforms[fields][25][]\" value=\"Telegram\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-5164-field_25_3\">Telegram<\/label><\/li><\/ul><\/div><div id=\"wpforms-5164-field_34-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpforms-list-2-columns\" data-field-id=\"34\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_34\">\u042f\u043a\u0430 \u043c\u043e\u0432\u0430?<\/label><ul id=\"wpforms-5164-field_34\"><li class=\"choice-1 depth-1 wpforms-selected\"><input type=\"radio\" id=\"wpforms-5164-field_34_1\" name=\"wpforms[fields][34]\" value=\"\u0410\u043d\u0433\u043b\u0438\u0439\u0441\u043a\u0438\u0439\"   checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-5164-field_34_1\">\u0410\u043d\u0433\u043b\u0456\u0439\u0441\u044c\u043a\u0430<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-5164-field_34_2\" name=\"wpforms[fields][34]\" value=\"\u0420\u0443\u0441\u0441\u043a\u0438\u0439\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-5164-field_34_2\">\u0423\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u0430<\/label><\/li><\/ul><\/div><div id=\"wpforms-5164-field_23-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_23\">\u0414\u0435 \u0432\u0430\u0448\u0435 \u0436\u0438\u0442\u043b\u043e \u0443 \u0413\u0443\u0434\u0430\u0443\u0440\u0456?<\/label><input type=\"text\" id=\"wpforms-5164-field_23\" class=\"wpforms-field-large\" name=\"wpforms[fields][23]\" placeholder=\"\u041d\u0430\u043f\u0438\u0448\u0456\u0442\u044c \u0442\u0443\u0442\" ><\/div><div id=\"wpforms-5164-field_24-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_24\">\u041a\u043e\u043c\u0435\u043d\u0442\u0430\u0440<\/label><textarea id=\"wpforms-5164-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\" placeholder=\"\u0422\u0443\u0442 \u0432\u0438 \u043c\u043e\u0436\u0435\u0442\u0435 \u0432\u043a\u0430\u0437\u0430\u0442\u0438 \u0441\u0432\u043e\u0457 \u043f\u043e\u0431\u0430\u0436\u0430\u043d\u043d\u044f \u0449\u043e\u0434\u043e \u0437\u0430\u043d\u044f\u0442\u0442\u044f \u0442\u0430 \u0456\u043d\u0441\u0442\u0440\u0443\u043a\u0442\u043e\u0440\u0430\" ><\/textarea><\/div><div id=\"wpforms-5164-field_26-container\" class=\"wpforms-field wpforms-field-payment-total booking-prepay\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_26\">\u041f\u0440\u0435\u0434\u043e\u043f\u043b\u0430\u0442\u0430 \u0431\u0440\u043e\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f 23% <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-payment-total\">0,00 \u20ac<\/div><input type=\"text\" id=\"wpforms-5164-field_26\" class=\"wpforms-field-required wpforms-payment-total\" data-rule-required-payment=\"1\" name=\"wpforms[fields][26]\" value=\"0\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" readonly=\"readonly\"><div class=\"wpforms-field-description\">\u041f\u043e\u0441\u043b\u0435 \u043e\u0442\u043f\u0440\u0430\u0432\u043a\u0438 \u0444\u043e\u0440\u043c\u044b \u0434\u043b\u044f \u043f\u043e\u0434\u0442\u0432\u0435\u0440\u0436\u0434\u0435\u043d\u0438\u044f \u0431\u0440\u043e\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u043e \u0432\u043d\u0435\u0441\u0442\u0438 \u043f\u0440\u0435\u0434\u043e\u043f\u043b\u0430\u0442\u0443 \u0432 \u0440\u0430\u0437\u043c\u0435\u0440\u0435 23% \u043e\u0442 \u0441\u0442\u043e\u0438\u043c\u043e\u0441\u0442\u0438.<\/div><\/div><div id=\"wpforms-5164-field_32-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-classic\" data-field-id=\"32\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_32\">\u0421\u043f\u043e\u0441\u0456\u0431 \u043e\u043f\u043b\u0430\u0442\u0438 <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-5164-field_32\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][32]\" required=\"required\"><option value=\"PayPal\"  selected='selected'>PayPal<\/option><option value=\"\u0411\u0430\u043d\u043a\u043e\u0432\u0441\u043a\u043e\u0439 \u043a\u0430\u0440\u0442\u043e\u0439\" >\u0411\u0430\u043d\u043a\u0456\u0432\u0441\u044c\u043a\u043e\u044e \u043a\u0430\u0440\u0442\u043a\u043e\u044e<\/option><\/select><\/div><div id=\"wpforms-5164-field_27-container\" class=\"wpforms-field wpforms-field-stripe-credit-card wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"27\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-5164-field_27\">\u041e\u043f\u043b\u0430\u0442\u0430 \u0431\u0430\u043d\u043a\u0456\u0432\u0441\u044c\u043a\u043e\u044e \u043a\u0430\u0440\u0442\u043a\u043e\u044e <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-stripe-credit-card-number\"><div id=\"wpforms-5164-field_27\" class=\"wpforms-field-stripe-credit-card-cardnumber wpforms-field-required\" data-required=\"required\"><!-- a Stripe Element will be inserted here. --><\/div><input type=\"text\" class=\"wpforms-stripe-credit-card-hidden-input\" name=\"wpforms[stripe-credit-card-hidden-input-5164]\" disabled style=\"display: none;\"><label for=\"wpforms-5164-field_27\" class=\"wpforms-field-sublabel after\">Card<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-stripe-credit-card-name\"><input type=\"text\" id=\"wpforms-5164-field_27-cardname\" class=\"wpforms-field-stripe-credit-card-cardname wpforms-field-required\" name=\"wpforms[stripe-credit-card-cardname]\" required><label for=\"wpforms-5164-field_27-cardname\" class=\"wpforms-field-sublabel after\">Name on Card<\/label><\/div><\/div><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"5164\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-5164\" class=\"wpforms-submit\" data-alt-text=\"\u041e\u0442\u043f\u0440\u0430\u0432\u043a\u0430...\" data-submit-text=\"\u041e\u0442\u043f\u0440\u0430\u0432\u0438\u0442\u044c\" aria-live=\"assertive\" value=\"wpforms-submit\">\u0412\u0456\u0434\u043f\u0440\u0430\u0432\u0438\u0442\u0438<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wintergudauri.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"uk\"\/><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0414\u043b\u044f \u0437\u0430\u043f\u043e\u0432\u043d\u0435\u043d\u043d\u044f \u0446\u0456\u0454\u0457 \u0444\u043e\u0440\u043c\u0438 \u0443\u0432\u0456\u043c\u043a\u043d\u0456\u0442\u044c JavaScript \u0443 \u0431\u0440\u0430\u0443\u0437\u0435\u0440\u0456.\u0414\u0430\u0442\u0430 *\u041f\u043e\u043b\u043e\u0432\u0438\u043d\u0430 \u0434\u043d\u044f\u0423\u0442\u0440\u043e: \u0434\u043e 10:00\u041f\u043e\u0441\u043b\u0435 \u043e\u0431\u0435\u0434\u0430: \u0441 16:00\u0421\u043a\u043e\u043b\u044c\u043a\u043e \u0447\u0435\u043b\u043e\u0432\u0435\u043a \/ \u0446\u0435\u043d\u0430 *1 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434 \/ 125 \u20ac2 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u0430 \/ 250 \u20ac3 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u0430 \/ 375 \u20ac4 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u0430 \/ 500 \u20ac5 \u0441\u043d\u0435\u0433\u043e\u0445\u043e\u0434\u043e\u0432 \/ 625 \u20ac\u041a\u043e\u043d\u0442\u0430\u043a\u0442\u043d\u044b\u0435 \u0434\u0430\u043d\u043d\u044b\u0435\u0418\u043c\u044f *\u0412\u043e\u0437\u0440\u0430\u0441\u0442 *\u0422\u0435\u043b\u0435\u0444\u043e\u043d *Email *\u041c\u0435\u0441\u0435\u043d\u0434\u0436\u0435\u0440 *WhatsAppViberTelegram\u041a\u0430\u043a\u043e\u0439 \u044f\u0437\u044b\u043a?\u0410\u043d\u0433\u043b\u0438\u0439\u0441\u043a\u0438\u0439\u0420\u0443\u0441\u0441\u043a\u0438\u0439\u0413\u0434\u0435 \u0432\u0430\u0448\u0435 \u0436\u0438\u043b\u044c\u0435 \u0432 \u0413\u0443\u0434\u0430\u0443\u0440\u0438?\u041a\u043e\u043c\u043c\u0435\u043d\u0442\u0430\u0440\u0438\u0439\u041f\u0440\u0435\u0434\u043e\u043f\u043b\u0430\u0442\u0430 \u0431\u0440\u043e\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f 23% *0,00 &euro;\u041f\u043e\u0441\u043b\u0435 \u043e\u0442\u043f\u0440\u0430\u0432\u043a\u0438&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-microsite.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5165","page","type-page","status-publish","hentry","description-off"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/pages\/5165"}],"collection":[{"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/comments?post=5165"}],"version-history":[{"count":1,"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/pages\/5165\/revisions"}],"predecessor-version":[{"id":5166,"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/pages\/5165\/revisions\/5166"}],"wp:attachment":[{"href":"https:\/\/wintergudauri.com\/uk\/wp-json\/wp\/v2\/media?parent=5165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}